{"id":1101,"date":"2026-03-18T10:45:13","date_gmt":"2026-03-18T09:45:13","guid":{"rendered":"https:\/\/www.sirene-plongee.com\/?post_type=trip&#038;p=1101"},"modified":"2026-05-12T13:56:32","modified_gmt":"2026-05-12T12:56:32","slug":"padi-master-seal-team","status":"publish","type":"trip","link":"https:\/\/www.sirene-plongee.com\/de\/nos-activites\/padi-master-seal-team\/","title":{"rendered":"PADI Master Seal Team"},"content":{"rendered":"<p>PADI Master Seal Team in Djerba \u2013 Tauchprogramm f\u00fcr Kinder im Club La Sir\u00e8ne<\/p>\n<p>Das PADI Master Seal Team Programm ist die zweite echte Tauchausbildung, die ein Kind absolvieren kann. Es ist der ideale Schritt nach dem PADI Seal Team f\u00fcr junge Taucher, die ihr Lernen vertiefen m\u00f6chten.<\/p>\n<p>Im Tauchclub La Sir\u00e8ne in Djerba bieten wir dieses spielerische und lehrreiche Programm an, das das Erlernen des Tauchens in ein spannendes Abenteuer verwandelt! La Sir\u00e8ne bietet eine sichere Umgebung, betreut von zertifizierten PADI-Tauchlehrern, damit Ihre Kinder zu echten kleinen Tauchern werden!<\/p>","protected":false},"excerpt":{"rendered":"<p>PADI Master Seal Team \u00e0 Djerba &#8211; Programme de plong\u00e9e pour enfants au club La Sir\u00e8ne Le programme PADI Master Seal Team est la deuxi\u00e8me v\u00e9ritable formation de plong\u00e9e qu&rsquo;un enfant peut suivre. C&rsquo;est l&rsquo;\u00e9tape id\u00e9ale apr\u00e8s le PADI Seal Team pour les jeunes plongeurs qui souhaitent aller plus loin dans leur apprentissage. Au club [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1378,"comment_status":"open","ping_status":"closed","template":"","destination":[],"activities":[39,65],"trip_types":[],"difficulty":[],"trip_tag":[],"class_list":["post-1101","trip","type-trip","status-publish","has-post-thumbnail","activities-formation-plongee","activities-padi-enfant"],"packages_ids":[1102],"trip_extras":[57,764],"cut_off_time":{"enabled":false,"duration":0,"duration_unit":"days"},"booked-seats":[],"trip_extra_services":[{"service_cost":"35","service_type":"default","service_unit":"unit","field_type":"select","pricing_type":"multiple-price","single_price":"35","options":[],"unit":[""],"default_descriptions":"Max 4 personnes \/ pack","title":"Fotos- und Videos-Paket"},{"service_cost":"15","service_type":"default","service_unit":"unit","field_type":"select","pricing_type":"multiple-price","single_price":"","options":[],"unit":[""],"default_descriptions":"Accompagner le plongeur sur le bateau","title":"Begleitung auf dem Boot"}],"acf":[],"code":"WTE-608","price":399,"has_sale":false,"sale_price":0,"discount_percent":0,"currency":{"code":"EUR","symbol":"&euro;"},"duration":{"days":3,"nights":0,"duration_unit":"days","duration_type":"days"},"primary_category":28,"available_times":{"type":"default","items":["2021-1-01","2021-2-01","2021-3-01","2021-4-01","2021-5-01","2021-6-01","2021-7-01","2021-8-01","2021-9-01","2021-10-01","2021-11-01","2021-12-01"]},"min_pax":"","max_pax":"","description":"","cost_includes":"","cost_excludes":"","itineraries":[],"faqs":[],"is_featured":false,"featured_image":{"width":960,"height":864,"file":"2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11.webp","filesize":41626,"sizes":{"medium":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-300x270.webp","width":300,"height":270,"filesize":6666,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-300x270.webp"},"thumbnail":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-150x150.webp","width":150,"height":150,"filesize":2852,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-150x150.webp"},"medium_large":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-768x691.webp","width":768,"height":691,"filesize":24370,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-768x691.webp"},"trip-thumb-size":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-374x226.webp","width":374,"height":226,"filesize":6776,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-374x226.webp"},"destination-thumb-size":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-600x810.webp","width":600,"height":810,"filesize":24822,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-600x810.webp"},"destination-thumb-trip-size":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-410x250.webp","width":410,"height":250,"filesize":7632,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-410x250.webp"},"activities-thumb-size":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-600x810.webp","width":600,"height":810,"filesize":24822,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-600x810.webp"},"trip-single-size":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-960x490.webp","width":960,"height":490,"filesize":24174,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-960x490.webp"},"woocommerce_thumbnail":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-300x300.webp","width":300,"height":300,"filesize":7338,"uncropped":false,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-300x300.webp"},"woocommerce_single":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-600x540.webp","width":600,"height":540,"filesize":17794,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-600x540.webp"},"woocommerce_gallery_thumbnail":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11-100x100.webp","width":100,"height":100,"filesize":1658,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11-100x100.webp"},"full":{"file":"WhatsApp-Image-2026-04-07-at-16.50.11.webp","width":960,"height":864,"source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.50.11.webp"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"_links":{"self":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip\/1101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip"}],"about":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/types\/trip"}],"author":[{"embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/comments?post=1101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/media\/1378"}],"wp:attachment":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/media?parent=1101"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/destination?post=1101"},{"taxonomy":"activities","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/activities?post=1101"},{"taxonomy":"trip_types","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip_types?post=1101"},{"taxonomy":"difficulty","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/difficulty?post=1101"},{"taxonomy":"trip_tag","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip_tag?post=1101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}