{"id":783,"date":"2026-02-03T14:07:25","date_gmt":"2026-02-03T13:07:25","guid":{"rendered":"https:\/\/www.sirene-plongee.com\/?post_type=trip&#038;p=783"},"modified":"2026-06-30T14:04:09","modified_gmt":"2026-06-30T13:04:09","slug":"padi-discover-scuba-diving","status":"publish","type":"trip","link":"https:\/\/www.sirene-plongee.com\/de\/nos-activites\/padi-discover-scuba-diving\/","title":{"rendered":"PADI Discover Scuba Diving"},"content":{"rendered":"<p>Willkommen in einer neuen Welt im Club La Sir\u00e8ne in Djerba!<br \/>\nDas PADI Discover Scuba Diving Programm \u00f6ffnet Ihnen die Tore zur blauen Planeten, wo Sie eine Umgebung entdecken werden, die noch reicher und aufregender ist, als Sie es sich vorstellen k\u00f6nnen. In den kristallklaren Gew\u00e4ssern von Djerba erm\u00f6glicht Ihnen dieses einzigartige Erlebnis, unvergessliche Momente unter der Oberfl\u00e4che zu erleben.<\/p>\n<p>Was k\u00f6nnen Sie von diesem Abenteuer erwarten?<br \/>\nVor allem viel Spa\u00df! Sie werden Ihre ersten Unterwasser-Atemz\u00fcge erleben, die Schwerelosigkeit sp\u00fcren und sich \u00fcber die Farben des Meereslebens begeistern, und dabei ein Gef\u00fchl vollst\u00e4ndiger Sicherheit genie\u00dfen. Begleitet von einem erfahrenen Fachmann des Clubs La Sir\u00e8ne wird Ihnen diese Erfahrung den Wunsch geben, immer wieder in die Unterwasserwelt von Djerba zur\u00fcckzukehren!<\/p>","protected":false},"excerpt":{"rendered":"<p>Bienvenue dans un nouveau monde au club La Sir\u00e8ne \u00e0 Djerba ! Le programme PADI Discover Scuba Diving vous ouvre les portes de la Plan\u00e8te Bleue, o\u00f9 vous d\u00e9couvrirez un environnement encore plus riche et passionnant que vous ne pouvez le imaginer. Dans les eaux cristallines de Djerba, cette exp\u00e9rience unique vous permettra de vivre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1400,"comment_status":"open","ping_status":"closed","template":"","destination":[],"activities":[41],"trip_types":[],"difficulty":[],"trip_tag":[],"class_list":["post-783","trip","type-trip","status-publish","has-post-thumbnail","activities-plongee-bouteille"],"packages_ids":[1079],"trip_extras":[57,764,765],"cut_off_time":{"enabled":false,"duration":0,"duration_unit":"days"},"booked-seats":[],"trip_extra_services":[{"service_cost":"35","service_type":"default","service_unit":"unit","field_type":"select","pricing_type":"multiple-price","single_price":"35","options":[],"unit":[""],"default_descriptions":"Max 4 personnes \/ pack","title":"Fotos- und Videos-Paket"},{"service_cost":"15","service_type":"default","service_unit":"unit","field_type":"select","pricing_type":"multiple-price","single_price":"","options":[],"unit":[""],"default_descriptions":"Accompagner le plongeur sur le bateau","title":"Begleitung auf dem Boot"},{"service_cost":"5","service_type":"default","service_unit":"unit","field_type":"select","pricing_type":"single-price","single_price":"","options":[],"unit":[""],"default_descriptions":"Prix par sortie","title":"Vermietung Tauchcomputer"}],"acf":[],"code":"WTE-608","price":89,"has_sale":false,"sale_price":0,"discount_percent":0,"currency":{"code":"EUR","symbol":"&euro;"},"duration":{"days":3,"nights":0,"duration_unit":"hours","duration_type":"days"},"primary_category":27,"available_times":{"type":"default","items":["2021-1-01","2021-2-01","2021-3-01","2021-4-01","2021-5-01","2021-6-01","2021-7-01","2021-8-01","2021-9-01","2021-10-01","2021-11-01","2021-12-01"]},"min_pax":"","max_pax":"","description":"","cost_includes":"","cost_excludes":"","itineraries":[],"faqs":[],"is_featured":false,"featured_image":{"width":1280,"height":960,"file":"2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30.webp","filesize":115432,"sizes":{"medium":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-300x225.webp","width":300,"height":225,"filesize":10848,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-300x225.webp"},"large":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-1024x768.webp","width":1024,"height":768,"filesize":65658,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-1024x768.webp"},"thumbnail":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-150x150.webp","width":150,"height":150,"filesize":4594,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-150x150.webp"},"medium_large":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-768x576.webp","width":768,"height":576,"filesize":44020,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-768x576.webp"},"trip-thumb-size":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-374x226.webp","width":374,"height":226,"filesize":13072,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-374x226.webp"},"destination-thumb-size":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-600x810.webp","width":600,"height":810,"filesize":42104,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-600x810.webp"},"destination-thumb-trip-size":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-410x250.webp","width":410,"height":250,"filesize":15100,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-410x250.webp"},"activities-thumb-size":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-600x810.webp","width":600,"height":810,"filesize":42104,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-600x810.webp"},"trip-single-size":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-990x490.webp","width":990,"height":490,"filesize":47902,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-990x490.webp"},"woocommerce_thumbnail":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-300x300.webp","width":300,"height":300,"filesize":12470,"uncropped":false,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-300x300.webp"},"woocommerce_single":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-600x450.webp","width":600,"height":450,"filesize":31124,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-600x450.webp"},"woocommerce_gallery_thumbnail":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30-100x100.webp","width":100,"height":100,"filesize":2440,"mime_type":"image\/webp","source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30-100x100.webp"},"full":{"file":"WhatsApp-Image-2026-04-07-at-16.59.30.webp","width":1280,"height":960,"source_url":"https:\/\/www.sirene-plongee.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-16.59.30.webp"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"_links":{"self":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip"}],"about":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/types\/trip"}],"author":[{"embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/comments?post=783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/media\/1400"}],"wp:attachment":[{"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/destination?post=783"},{"taxonomy":"activities","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/activities?post=783"},{"taxonomy":"trip_types","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip_types?post=783"},{"taxonomy":"difficulty","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/difficulty?post=783"},{"taxonomy":"trip_tag","embeddable":true,"href":"https:\/\/www.sirene-plongee.com\/de\/wp-json\/wp\/v2\/trip_tag?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}